{"id":130,"count":1,"description":"","link":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/tag\/prospecta-global-solutions\/","name":"Prospecta Global Solutions","slug":"prospecta-global-solutions","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivos Prospecta Global Solutions - Blue Studio Express<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/tag\/prospecta-global-solutions\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Prospecta Global Solutions - Blue Studio Express\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/tag\/prospecta-global-solutions\/\" \/>\n<meta property=\"og:site_name\" content=\"Blue Studio Express\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/tag\/prospecta-global-solutions\/\",\"url\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/tag\/prospecta-global-solutions\/\",\"name\":\"Arquivos Prospecta Global Solutions - Blue Studio Express\",\"isPartOf\":{\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/tag\/prospecta-global-solutions\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/tag\/prospecta-global-solutions\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prospecta Global Solutions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/#website\",\"url\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/\",\"name\":\"Blue Studio Express\",\"description\":\"Conte\u00fado relevante produzido por quem entende do assunto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Prospecta Global Solutions - Blue Studio Express","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/tag\/prospecta-global-solutions\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos Prospecta Global Solutions - Blue Studio Express","og_url":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/tag\/prospecta-global-solutions\/","og_site_name":"Blue Studio Express","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/tag\/prospecta-global-solutions\/","url":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/tag\/prospecta-global-solutions\/","name":"Arquivos Prospecta Global Solutions - Blue Studio Express","isPartOf":{"@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/#website"},"breadcrumb":{"@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/tag\/prospecta-global-solutions\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/tag\/prospecta-global-solutions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/"},{"@type":"ListItem","position":2,"name":"Prospecta Global Solutions"}]},{"@type":"WebSite","@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/#website","url":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/","name":"Blue Studio Express","description":"Conte\u00fado relevante produzido por quem entende do assunto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/tags\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/posts?tags=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}