{"id":10670,"date":"2025-02-06T07:48:11","date_gmt":"2025-02-06T10:48:11","guid":{"rendered":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/?p=10670"},"modified":"2025-02-06T07:49:59","modified_gmt":"2025-02-06T10:49:59","slug":"como-os-volumes-de-carga-aerea-sao-inspecionados","status":"publish","type":"post","link":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/","title":{"rendered":"Como os volumes de carga a\u00e9rea s\u00e3o inspecionados?"},"content":{"rendered":"<figure class=\"gh-styles-m__figureContainer\" style=\"float: undefined; text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10767\" src=\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-content\/uploads\/2025\/02\/pexelstomfisk10636506-1.jpeg\" alt=\"\" width=\"1279\" height=\"956\" srcset=\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-content\/uploads\/2025\/02\/pexelstomfisk10636506-1.jpeg 1279w, https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-content\/uploads\/2025\/02\/pexelstomfisk10636506-1-300x224.jpeg 300w, https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-content\/uploads\/2025\/02\/pexelstomfisk10636506-1-768x574.jpeg 768w, https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-content\/uploads\/2025\/02\/pexelstomfisk10636506-1-1024x765.jpeg 1024w, https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-content\/uploads\/2025\/02\/pexelstomfisk10636506-1-710x531.jpeg 710w\" sizes=\"auto, (max-width: 1279px) 100vw, 1279px\" \/><figcaption class=\"gh-styles-m__figureContainer-caption\">Foto de Tom Fisk no Pexels<\/figcaption><\/figure>\n<p>Assim como ocorre com o transporte de passageiros, a seguran\u00e7a da carga a\u00e9rea \u00e9 um dos pilares de sustenta\u00e7\u00e3o da avia\u00e7\u00e3o. O processo de inspe\u00e7\u00e3o das mercadorias que trafegam tanto no mercado dom\u00e9stico quanto internacional segue crit\u00e9rios rigorosos para garantir a integridade de todos e, tamb\u00e9m, para combater poss\u00edveis ilegalidades.<\/p>\n<p>No \u00faltimo ano, o Brasil transportou 1,54 milh\u00e3o de toneladas de cargas em 925 mil decolagens, de acordo com <a href=\"https:\/\/www.gov.br\/anac\/pt-br\/noticias\/2025\/com-118-milhoes-de-passageiros-transportados-em-2024-setor-aereo-tem-segundo-melhor-desempenhos-da-historia\" target=\"_blank\" rel=\"noopener\" data-type=\"LINK\">relat\u00f3rio da Ag\u00eancia Nacional de Avia\u00e7\u00e3o Civil<\/a>, a Anac.<\/p>\n<p>Entre outros fatores, o desenvolvimento do setor registrado em n\u00fameros tem liga\u00e7\u00e3o direta com a seguran\u00e7a da carga a\u00e9rea. Afinal, al\u00e9m da agilidade, o servi\u00e7o est\u00e1 atrelado \u00e0 efici\u00eancia e \u00e0 confiabilidade.<\/p>\n<p>A combina\u00e7\u00e3o desses ingredientes trouxe os olhares das empresas para o transporte a\u00e9reo de cargas, seja para o envio r\u00e1pido de produtos sens\u00edveis, como medicamentos, seja para o sucesso do e-commerce, permitindo que os produtos cheguem na casa dos clientes em menos de 24 horas, mesmo em locais remotos.<\/p>\n<!-- In\u00edcio Banner 300x250 --><div class='dfp-tmeio1'><\/div><script type='text\/javascript'>DFP.renderHtml({ 'selector':'div.dfp-tmeio1', 'targets':{ 'formato':'tmeio1' }, 'screenmap':'Tile_300_250_T_250', 'force': true });<\/script><!-- Fim Banner 300x250 --> <p>A efici\u00eancia do servi\u00e7o, por\u00e9m, atraiu tamb\u00e9m a aten\u00e7\u00e3o de criminosos e terroristas, cada vez mais sofisticados. Por isso, o trabalho de seguran\u00e7a da carga a\u00e9rea exige um aprimoramento permanente, com o suporte de novas tecnologias, o aprimoramento constante das equipes e, tamb\u00e9m, dos processos, com base em regulamentos bastante rigorosos.<\/p>\n<p>Mas como isso funciona na pr\u00e1tica? Para entender melhor sobre o assunto, vale ficar por dentro do sistema de seguran\u00e7a dos aeroportos.<\/p>\n<h2><strong>Seguran\u00e7a da carga a\u00e9rea<\/strong><\/h2>\n<p>Os processos de inspe\u00e7\u00e3o e seguran\u00e7a, envolvidos no transporte a\u00e9reo de cargas, seguem crit\u00e9rios rigorosos e constantemente atualizados, sempre de acordo com as normais internacionais que regem o tema.<\/p>\n<p>Quando o assunto \u00e9 seguran\u00e7a em aeroportos, os usu\u00e1rios logo t\u00eam em mente a inspe\u00e7\u00e3o de passageiros e de bagagem de m\u00e3o, regulamentada pela <a href=\"https:\/\/www.anac.gov.br\/assuntos\/legislacao\/legislacao-1\/resolucoes\/2019\/resolucao-no-515-08-05-2019\" target=\"_blank\" rel=\"noopener\" data-type=\"LINK\">resolu\u00e7\u00e3o n\u00ba 515, de 2019<\/a>, da Anac.<\/p>\n<p>Chamada popularmente como \u201crevista pessoal\u201d, esse procedimento tem por objetivo combater \u201catos de interfer\u00eancia il\u00edcita nos aeroportos\u201d. Nesse caso, o documento traz detalhadamente os procedimentos que precisam ser adotados para evitar transtornos durante os voos.<\/p>\n<p>Entretanto, \u00e9 importante lembrar tamb\u00e9m sobre a inspe\u00e7\u00e3o realizada nas cargas para verificar a integridade e legalidade dos produtos transportados nas aeronaves.<\/p>\n<p>Procedimento previsto na <a href=\"https:\/\/www.anac.gov.br\/assuntos\/legislacao\/legislacao-1\/rbha-e-rbac\/rbac\/rbac-107\" target=\"_blank\" rel=\"noopener\" data-type=\"LINK\">Emenda 9 ao RBAC n\u00ba 107 da Anac<\/a>, como responsabilidade do administrador do aeroporto, a carga a\u00e9rea deve permanecer sob constante vigil\u00e2ncia at\u00e9 ser transferida para a empresa a\u00e9rea.<\/p>\n<p>Al\u00e9m dos detalhes sobre a carga estarem descritos em documento apropriado, a inspe\u00e7\u00e3o dos itens transportados pode ocorrer em diferentes momentos.<\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/in\/flaviomonteze\" target=\"_blank\" rel=\"noopener\" data-type=\"LINK\">Fl\u00e1vio Monteze<\/a>, s\u00f3cio da empresa <a href=\"https:\/\/apzi.com.br\/cursos\/\" target=\"_blank\" rel=\"noopener\" data-type=\"LINK\">Apzi Treinamentos<\/a> afirrma: &#8220;Geralmente, o uso do aparelho de raios-x permite uma an\u00e1lise minuciosa sobre a integridade da mercadoria. Mas o teor da carga tamb\u00e9m pode exigir vistorias mais espec\u00edficas, como a utiliza\u00e7\u00e3o de detectores de explosivos ou de c\u00e3es farejadores&#8221;.<\/p>\n<h2>Estrutura e qualifica\u00e7\u00e3o<\/h2>\n<p>Todo esse processo de fiscaliza\u00e7\u00e3o exige um trabalho coordenado e bem executado nos aeroportos brasileiros, com a atua\u00e7\u00e3o conjunta de diferentes agentes. A come\u00e7ar pelos investimentos constantes em estrutura e novas tecnologias.<\/p>\n<p>Outro ponto muito importante para a seguran\u00e7a do transporte a\u00e9reo de cargas \u00e9 a forma\u00e7\u00e3o dos profissionais que atuam nessa \u00e1rea. Al\u00e9m do cumprimento obrigat\u00f3rio de determinados requisitos legais, esses colaboradores necessitam e qualifica\u00e7\u00e3o constante e permanente.<\/p>\n<p>Como exemplo, podemos citar dois cursos <a href=\"https:\/\/apzi.com.br\/\" target=\"_blank\" rel=\"noopener\" data-type=\"LINK\">Apzi<\/a>, empresa brasileira com foco na qualifica\u00e7\u00e3o profissional de aerovi\u00e1rios, aeronautas e profissionais de com\u00e9rcio exterior.<\/p>\n<p>O curso &#8220;Seguran\u00e7a da Carga A\u00e9rea&#8217; (AVSEC)&#8221; \u00e9 espec\u00edfico para a especializa\u00e7\u00e3o de profissionais que almejam trabalhar com o transporte de mercadorias por via a\u00e9rea. Por sua vez, o curso &#8220;Transporte A\u00e9reo de Artigos Perigosos (DGR)&#8221; garante o conhecimento necess\u00e1rio para a seguran\u00e7a e conformidade no manuseio e transporte de cargas contendo artigos perigosos.<\/p>\n<p>Certamente, o desenvolvimento do transporte a\u00e9reo est\u00e1 atrelado com a seguran\u00e7a da carga movimentada nos aeroportos. Dessa forma, a expans\u00e3o do setor tem liga\u00e7\u00e3o direta com os investimentos em estrutura e tecnologia, assim como na qualifica\u00e7\u00e3o dos profissionais.<\/p>\n<p>Quer saber mais sobre este e outros temas relacionados com a avia\u00e7\u00e3o? Ent\u00e3o acesse o site <a href=\"https:\/\/apzi.com.br\/\" target=\"_blank\" rel=\"noopener\" data-type=\"LINK\">https:\/\/apzi.com.br<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A seguran\u00e7a da carga a\u00e9rea \u00e9 um dos pilares para o desenvolvimento do transporte a\u00e9reo no Brasil e no mundo.<\/p>\n","protected":false},"author":3,"featured_media":10767,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[224],"class_list":["post-10670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","tag-apzi-consultoria-e-treinamentos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Como os volumes de carga a\u00e9rea s\u00e3o inspecionados? | Blue Studio Express<\/title>\n<meta name=\"description\" content=\"A seguran\u00e7a da carga a\u00e9rea \u00e9 um dos pilares para o desenvolvimento do transporte a\u00e9reo no Brasil e no mundo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como os volumes de carga a\u00e9rea s\u00e3o inspecionados? | Blue Studio Express\" \/>\n<meta property=\"og:description\" content=\"A seguran\u00e7a da carga a\u00e9rea \u00e9 um dos pilares para o desenvolvimento do transporte a\u00e9reo no Brasil e no mundo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/\" \/>\n<meta property=\"og:site_name\" content=\"Blue Studio Express\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-06T10:48:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T10:49:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-content\/uploads\/2025\/02\/pexelstomfisk10636506-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1279\" \/>\n\t<meta property=\"og:image:height\" content=\"956\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Estad\u00e3o Blue Studio Express\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Estad\u00e3o Blue Studio Express\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/\",\"url\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/\",\"name\":\"Como os volumes de carga a\u00e9rea s\u00e3o inspecionados? | Blue Studio Express\",\"isPartOf\":{\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-content\/uploads\/2025\/02\/pexelstomfisk10636506-1.jpeg\",\"datePublished\":\"2025-02-06T10:48:11+00:00\",\"dateModified\":\"2025-02-06T10:49:59+00:00\",\"author\":{\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/#\/schema\/person\/be853092d40afd1b8888ddee21865a1b\"},\"description\":\"A seguran\u00e7a da carga a\u00e9rea \u00e9 um dos pilares para o desenvolvimento do transporte a\u00e9reo no Brasil e no mundo.\",\"breadcrumb\":{\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/#primaryimage\",\"url\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-content\/uploads\/2025\/02\/pexelstomfisk10636506-1.jpeg\",\"contentUrl\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-content\/uploads\/2025\/02\/pexelstomfisk10636506-1.jpeg\",\"width\":1279,\"height\":956},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como os volumes de carga a\u00e9rea s\u00e3o inspecionados?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/#website\",\"url\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/\",\"name\":\"Blue Studio Express\",\"description\":\"Conte\u00fado relevante produzido por quem entende do assunto\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/#\/schema\/person\/be853092d40afd1b8888ddee21865a1b\",\"name\":\"Estad\u00e3o Blue Studio Express\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/196f334a3798a907d9263f7a01624df232b56dc4315bf278df7fcca47d35a19b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/196f334a3798a907d9263f7a01624df232b56dc4315bf278df7fcca47d35a19b?s=96&d=mm&r=g\",\"caption\":\"Estad\u00e3o Blue Studio Express\"},\"url\":\"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/author\/fabiolemos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como os volumes de carga a\u00e9rea s\u00e3o inspecionados? | Blue Studio Express","description":"A seguran\u00e7a da carga a\u00e9rea \u00e9 um dos pilares para o desenvolvimento do transporte a\u00e9reo no Brasil e no mundo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/","og_locale":"pt_BR","og_type":"article","og_title":"Como os volumes de carga a\u00e9rea s\u00e3o inspecionados? | Blue Studio Express","og_description":"A seguran\u00e7a da carga a\u00e9rea \u00e9 um dos pilares para o desenvolvimento do transporte a\u00e9reo no Brasil e no mundo.","og_url":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/","og_site_name":"Blue Studio Express","article_published_time":"2025-02-06T10:48:11+00:00","article_modified_time":"2025-02-06T10:49:59+00:00","og_image":[{"width":1279,"height":956,"url":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-content\/uploads\/2025\/02\/pexelstomfisk10636506-1.jpeg","type":"image\/jpeg"}],"author":"Estad\u00e3o Blue Studio Express","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Estad\u00e3o Blue Studio Express","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/","url":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/","name":"Como os volumes de carga a\u00e9rea s\u00e3o inspecionados? | Blue Studio Express","isPartOf":{"@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/#primaryimage"},"image":{"@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/#primaryimage"},"thumbnailUrl":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-content\/uploads\/2025\/02\/pexelstomfisk10636506-1.jpeg","datePublished":"2025-02-06T10:48:11+00:00","dateModified":"2025-02-06T10:49:59+00:00","author":{"@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/#\/schema\/person\/be853092d40afd1b8888ddee21865a1b"},"description":"A seguran\u00e7a da carga a\u00e9rea \u00e9 um dos pilares para o desenvolvimento do transporte a\u00e9reo no Brasil e no mundo.","breadcrumb":{"@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/#primaryimage","url":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-content\/uploads\/2025\/02\/pexelstomfisk10636506-1.jpeg","contentUrl":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-content\/uploads\/2025\/02\/pexelstomfisk10636506-1.jpeg","width":1279,"height":956},{"@type":"BreadcrumbList","@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/2025\/02\/06\/como-os-volumes-de-carga-aerea-sao-inspecionados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/"},{"@type":"ListItem","position":2,"name":"Como os volumes de carga a\u00e9rea s\u00e3o inspecionados?"}]},{"@type":"WebSite","@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/#website","url":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/","name":"Blue Studio Express","description":"Conte\u00fado relevante produzido por quem entende do assunto","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/#\/schema\/person\/be853092d40afd1b8888ddee21865a1b","name":"Estad\u00e3o Blue Studio Express","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/196f334a3798a907d9263f7a01624df232b56dc4315bf278df7fcca47d35a19b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/196f334a3798a907d9263f7a01624df232b56dc4315bf278df7fcca47d35a19b?s=96&d=mm&r=g","caption":"Estad\u00e3o Blue Studio Express"},"url":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/author\/fabiolemos\/"}]}},"_links":{"self":[{"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/posts\/10670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/comments?post=10670"}],"version-history":[{"count":26,"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/posts\/10670\/revisions"}],"predecessor-version":[{"id":10770,"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/posts\/10670\/revisions\/10770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/media\/10767"}],"wp:attachment":[{"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/media?parent=10670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/categories?post=10670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bluestudioexpress.estadao.com.br\/conteudo\/wp-json\/wp\/v2\/tags?post=10670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}